{"id":94006,"date":"2026-09-01T08:44:15","date_gmt":"2026-09-01T14:44:15","guid":{"rendered":"https:\/\/thebelizecollection.com\/marlas-house-of-hope\/"},"modified":"2026-09-01T08:55:25","modified_gmt":"2026-09-01T14:55:25","slug":"marlas-house-of-hope","status":"publish","type":"page","link":"https:\/\/thebelizecollection.com\/fr\/marlas-house-of-hope\/","title":{"rendered":"La Maison de l\u2019Espoir de Marla"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"94006\" class=\"elementor elementor-94006 elementor-93948\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a87a499 e-con-full e-flex e-con e-parent\" data-id=\"a87a499\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-321244d e-flex e-con-boxed e-con e-parent\" data-id=\"321244d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-84a991f elementor-widget elementor-widget-image\" data-id=\"84a991f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/thebelizecollection.com\/wp-content\/uploads\/2025\/04\/the-Belize-collection-flower-logo.png\" class=\"attachment-full size-full wp-image-74305\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e612a58 e-flex e-con-boxed e-con e-parent\" data-id=\"e612a58\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;video&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b372d67 elementor-widget elementor-widget-heading\" data-id=\"b372d67\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">La Maison de l\u2019Espoir de Marla<\/h1>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1b610b3 e-flex e-con-boxed elementor-invisible e-con e-parent\" data-id=\"1b610b3\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-020d69f elementor-widget elementor-widget-text-editor\" data-id=\"020d69f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3fd73d8 elementor-widget elementor-widget-text-editor\" data-id=\"3fd73d8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\"><div class=\"elementor-widget-container\"><p>La Maison de l\u2019Espoir de Marla est un foyer pour enfants d\u00e9di\u00e9 \u00e0 offrir des soins bienveillants \u00e0 des filles retir\u00e9es de milieux abusifs. Le D\u00e9partement des services sociaux retire les enfants de foyers o\u00f9 ils ont subi un certain degr\u00e9 de maltraitance et les place \u00e0 la Maison de l\u2019Espoir de Marla. Une fois chez Marla, la m\u00e8re sup\u00e9rieure, le personnel et les b\u00e9n\u00e9voles accompagnent ces enfants, qui ont souvent du mal \u00e0 s\u2019adapter \u00e0 une vie \u00ab normale \u00bb. Ils leur transmettent amour, \u00e9ducation, discipline et soutien. Dans certains cas, les enfants peuvent \u00eatre r\u00e9unis avec leurs parents. Dans d\u2019autres, Marla assure une prise en charge \u00e0 long terme et les pr\u00e9pare \u00e0 une vie d\u2019adulte responsable.     <\/p><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8e7b20d e-flex e-con-boxed e-con e-parent\" data-id=\"8e7b20d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-5686d04 e-con-full e-flex e-con e-child\" data-id=\"5686d04\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c8cd994 e-con-full e-flex e-con e-child\" data-id=\"c8cd994\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e606f15 elementor-widget elementor-widget-heading\" data-id=\"e606f15\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Comment tout a commenc\u00e9<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a4c9be0 elementor-widget elementor-widget-text-editor\" data-id=\"a4c9be0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Marla&#8217;s House of Hope a d\u00e9but\u00e9 sous la forme d&#8217;un comit\u00e9 form\u00e9 par la Dr Marla Holder pour lutter contre la maltraitance et l&#8217;exploitation des enfants au Belize. Un an plus tard, la Dr Holder est d\u00e9c\u00e9d\u00e9e dans un tragique accident en tentant de sauver un enfant de la noyade. En 1998, le premier centre d&#8217;accueil pour enfants a \u00e9t\u00e9 ouvert par le D\u00e9partement des services sociaux et nomm\u00e9 \u00ab Marla&#8217;s House of Hope \u00bb en l&#8217;honneur de la Dr Marla Holder. Gr\u00e2ce \u00e0 l&#8217;aide de la communaut\u00e9 d&#8217;affaires locale ainsi que d&#8217;amis et d&#8217;entreprises des \u00c9tats-Unis, Marla&#8217;s House of Hope a pu construire un foyer permanent o\u00f9 r\u00e9sident d\u00e9sormais 20 enfants. Au cours des 20 derni\u00e8res ann\u00e9es, 400 enfants ont \u00e9t\u00e9 pris en charge par Marla&#8217;s House of Hope.    <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0ad85cb elementor-widget elementor-widget-heading\" data-id=\"0ad85cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Notre partenariat<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-86b0f0b elementor-widget elementor-widget-text-editor\" data-id=\"86b0f0b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3fd73d8 elementor-widget elementor-widget-text-editor\" data-id=\"3fd73d8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\"><div class=\"elementor-widget-container\"><p>Dans les halls de nos resorts, The Belize Collection expose fi\u00e8rement des peintures r\u00e9alis\u00e9es avec soin par les filles vivant \u00e0 la Maison de l\u2019Espoir de Marla. Les clients sont invit\u00e9s \u00e0 emporter une peinture en \u00e9change d\u2019un don du montant de leur choix afin de soutenir les filles b\u00e9n\u00e9ficiant de soins bienveillants \u00e0 la Maison de l\u2019Espoir de Marla. <\/p><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9d39417 e-flex e-con-boxed e-con e-parent\" data-id=\"9d39417\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-cfbf529 e-con-full e-flex e-con e-child\" data-id=\"cfbf529\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f5a8147 elementor-widget elementor-widget-heading\" data-id=\"f5a8147\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Faire un don<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b73e526 elementor-widget elementor-widget-text-editor\" data-id=\"b73e526\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Si vous voyagez vers les resorts The Belize Collection et que vous avez de la place dans vos bagages, nous avons contact\u00e9 la m\u00e8re sup\u00e9rieure, qui a \u00e9tabli une liste de besoins :<\/span><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Grands sacs de rangement transparents<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Tongs et sandales habill\u00e9es de toutes tailles (jusqu\u2019\u00e0 la pointure 11)<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Dentifrice pour adultes<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Shampooing antipelliculaire<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Produits de soin pour b\u00e9b\u00e9<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Soutiens-gorge de toutes tailles (tour de dos 24-40) (bonnets A \u00e0 DD)<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Oreillers de taille standard<\/span><\/li><\/ul><p><span style=\"font-weight: 400;\">Si vous souhaitez apporter une aide financi\u00e8re, cliquez sur le bouton de don. Merci de prendre soin des enfants du Belize. <\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f979c2e elementor-widget elementor-widget-button\" data-id=\"f979c2e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.marlashouseofhope.org\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">FAIRE UN DON MAINTENANT<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ef2cb5d e-con-full e-flex e-con e-child\" data-id=\"ef2cb5d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bdc926c e-flex e-con-boxed e-con e-parent\" data-id=\"bdc926c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a76b884 elementor-widget elementor-widget-spacer\" data-id=\"a76b884\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>La Maison de l\u2019Espoir de Marla La Maison de l\u2019Espoir de Marla est un foyer pour enfants d\u00e9di\u00e9 \u00e0 offrir des soins bienveillants \u00e0 des filles retir\u00e9es de milieux abusifs. Le D\u00e9partement des services sociaux retire les enfants de foyers o\u00f9 ils ont subi un certain degr\u00e9 de maltraitance et les place \u00e0 la Maison [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":93970,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-full-width.php","meta":{"_acf_changed":false,"_vp_format_video_url":"","_vp_image_focal_point":[],"footnotes":""},"categories":[],"tags":[],"class_list":["post-94006","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Maison de l\u2019Espoir de Marla - The Belize Collection<\/title>\n<meta name=\"description\" content=\"La Maison de l\u2019Espoir de Marla est un foyer pour enfants d\u00e9di\u00e9 \u00e0 offrir des soins bienveillants \u00e0 des filles retir\u00e9es de milieux abusifs.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/thebelizecollection.com\/fr\/marlas-house-of-hope\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Maison de l\u2019Espoir de Marla - The Belize Collection\" \/>\n<meta property=\"og:description\" content=\"La Maison de l\u2019Espoir de Marla est un foyer pour enfants d\u00e9di\u00e9 \u00e0 offrir des soins bienveillants \u00e0 des filles retir\u00e9es de milieux abusifs.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/thebelizecollection.com\/fr\/marlas-house-of-hope\/\" \/>\n<meta property=\"og:site_name\" content=\"The Belize Collection\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-01T14:55:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/thebelizecollection.com\/wp-content\/uploads\/2026\/09\/home-banner-1a-1_WebOpd.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1620\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/thebelizecollection.com\\\/fr\\\/marlas-house-of-hope\\\/\",\"url\":\"https:\\\/\\\/thebelizecollection.com\\\/fr\\\/marlas-house-of-hope\\\/\",\"name\":\"La Maison de l\u2019Espoir de Marla - The Belize Collection\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thebelizecollection.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/thebelizecollection.com\\\/fr\\\/marlas-house-of-hope\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/thebelizecollection.com\\\/fr\\\/marlas-house-of-hope\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/thebelizecollection.com\\\/wp-content\\\/uploads\\\/2026\\\/09\\\/home-banner-1a-1_WebOpd.jpg\",\"datePublished\":\"2026-09-01T14:44:15+00:00\",\"dateModified\":\"2026-09-01T14:55:25+00:00\",\"description\":\"La Maison de l\u2019Espoir de Marla est un foyer pour enfants d\u00e9di\u00e9 \u00e0 offrir des soins bienveillants \u00e0 des filles retir\u00e9es de milieux abusifs.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/thebelizecollection.com\\\/fr\\\/marlas-house-of-hope\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/thebelizecollection.com\\\/fr\\\/marlas-house-of-hope\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/thebelizecollection.com\\\/fr\\\/marlas-house-of-hope\\\/#primaryimage\",\"url\":\"https:\\\/\\\/thebelizecollection.com\\\/wp-content\\\/uploads\\\/2026\\\/09\\\/home-banner-1a-1_WebOpd.jpg\",\"contentUrl\":\"https:\\\/\\\/thebelizecollection.com\\\/wp-content\\\/uploads\\\/2026\\\/09\\\/home-banner-1a-1_WebOpd.jpg\",\"width\":1620,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/thebelizecollection.com\\\/fr\\\/marlas-house-of-hope\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/thebelizecollection.com\\\/fr\\\/the-belize-collection-2\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Maison de l\u2019Espoir de Marla\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/thebelizecollection.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/thebelizecollection.com\\\/fr\\\/\",\"name\":\"The Belize Collection\",\"description\":\"Everything Belize\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/thebelizecollection.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Maison de l\u2019Espoir de Marla - The Belize Collection","description":"La Maison de l\u2019Espoir de Marla est un foyer pour enfants d\u00e9di\u00e9 \u00e0 offrir des soins bienveillants \u00e0 des filles retir\u00e9es de milieux abusifs.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/thebelizecollection.com\/fr\/marlas-house-of-hope\/","og_locale":"fr_FR","og_type":"article","og_title":"La Maison de l\u2019Espoir de Marla - The Belize Collection","og_description":"La Maison de l\u2019Espoir de Marla est un foyer pour enfants d\u00e9di\u00e9 \u00e0 offrir des soins bienveillants \u00e0 des filles retir\u00e9es de milieux abusifs.","og_url":"https:\/\/thebelizecollection.com\/fr\/marlas-house-of-hope\/","og_site_name":"The Belize Collection","article_modified_time":"2026-09-01T14:55:25+00:00","og_image":[{"width":1620,"height":1080,"url":"https:\/\/thebelizecollection.com\/wp-content\/uploads\/2026\/09\/home-banner-1a-1_WebOpd.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/thebelizecollection.com\/fr\/marlas-house-of-hope\/","url":"https:\/\/thebelizecollection.com\/fr\/marlas-house-of-hope\/","name":"La Maison de l\u2019Espoir de Marla - The Belize Collection","isPartOf":{"@id":"https:\/\/thebelizecollection.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/thebelizecollection.com\/fr\/marlas-house-of-hope\/#primaryimage"},"image":{"@id":"https:\/\/thebelizecollection.com\/fr\/marlas-house-of-hope\/#primaryimage"},"thumbnailUrl":"https:\/\/thebelizecollection.com\/wp-content\/uploads\/2026\/09\/home-banner-1a-1_WebOpd.jpg","datePublished":"2026-09-01T14:44:15+00:00","dateModified":"2026-09-01T14:55:25+00:00","description":"La Maison de l\u2019Espoir de Marla est un foyer pour enfants d\u00e9di\u00e9 \u00e0 offrir des soins bienveillants \u00e0 des filles retir\u00e9es de milieux abusifs.","breadcrumb":{"@id":"https:\/\/thebelizecollection.com\/fr\/marlas-house-of-hope\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/thebelizecollection.com\/fr\/marlas-house-of-hope\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/thebelizecollection.com\/fr\/marlas-house-of-hope\/#primaryimage","url":"https:\/\/thebelizecollection.com\/wp-content\/uploads\/2026\/09\/home-banner-1a-1_WebOpd.jpg","contentUrl":"https:\/\/thebelizecollection.com\/wp-content\/uploads\/2026\/09\/home-banner-1a-1_WebOpd.jpg","width":1620,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/thebelizecollection.com\/fr\/marlas-house-of-hope\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/thebelizecollection.com\/fr\/the-belize-collection-2\/"},{"@type":"ListItem","position":2,"name":"La Maison de l\u2019Espoir de Marla"}]},{"@type":"WebSite","@id":"https:\/\/thebelizecollection.com\/fr\/#website","url":"https:\/\/thebelizecollection.com\/fr\/","name":"The Belize Collection","description":"Everything Belize","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/thebelizecollection.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/thebelizecollection.com\/fr\/wp-json\/wp\/v2\/pages\/94006","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thebelizecollection.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/thebelizecollection.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/thebelizecollection.com\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/thebelizecollection.com\/fr\/wp-json\/wp\/v2\/comments?post=94006"}],"version-history":[{"count":4,"href":"https:\/\/thebelizecollection.com\/fr\/wp-json\/wp\/v2\/pages\/94006\/revisions"}],"predecessor-version":[{"id":94023,"href":"https:\/\/thebelizecollection.com\/fr\/wp-json\/wp\/v2\/pages\/94006\/revisions\/94023"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/thebelizecollection.com\/fr\/wp-json\/wp\/v2\/media\/93970"}],"wp:attachment":[{"href":"https:\/\/thebelizecollection.com\/fr\/wp-json\/wp\/v2\/media?parent=94006"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/thebelizecollection.com\/fr\/wp-json\/wp\/v2\/categories?post=94006"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/thebelizecollection.com\/fr\/wp-json\/wp\/v2\/tags?post=94006"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}